{"id":17,"count":20,"description":"","link":"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/","name":"Portada","slug":"portada","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portada archivos - Centro Juvenil Acuarela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portada archivos - Centro Juvenil Acuarela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Juvenil Acuarela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/category\\\/portada\\\/\",\"url\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/category\\\/portada\\\/\",\"name\":\"Portada archivos - Centro Juvenil Acuarela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/category\\\/portada\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/category\\\/portada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/#website\",\"url\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/\",\"name\":\"Centro Juvenil Acuarela\",\"description\":\"P\u00e1gina oficial Salesianos La L\u00ednea de la Concepci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portada archivos - Centro Juvenil Acuarela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/","og_locale":"es_ES","og_type":"article","og_title":"Portada archivos - Centro Juvenil Acuarela","og_url":"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/","og_site_name":"Centro Juvenil Acuarela","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/","url":"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/","name":"Portada archivos - Centro Juvenil Acuarela","isPartOf":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/#website"},"breadcrumb":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/category\/portada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lalinea.salesianos.edu\/mjs\/"},{"@type":"ListItem","position":2,"name":"Portada"}]},{"@type":"WebSite","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/#website","url":"https:\/\/lalinea.salesianos.edu\/mjs\/","name":"Centro Juvenil Acuarela","description":"P\u00e1gina oficial Salesianos La L\u00ednea de la Concepci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lalinea.salesianos.edu\/mjs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}