{"id":5165,"date":"2024-05-28T13:21:21","date_gmt":"2024-05-28T11:21:21","guid":{"rendered":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/"},"modified":"2025-08-04T10:55:03","modified_gmt":"2025-08-04T08:55:03","slug":"festividad-de-maria-auxiliadora-3","status":"publish","type":"post","link":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/","title":{"rendered":"Festividad de Mar\u00eda Auxiliadora"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbAutor\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><em>Por ADMA &#8211; Archicofrad\u00eda de MAr\u00eda Auxiliadora<\/em><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbCuerpo\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb text_line_height=\u00bb1.4em\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">Y LLEG\u00d3 EL 25 DE MAYO\u2026. Y SEGUIMOS SO\u00d1ANDO<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Ayer fue un d\u00eda emotivo, de nervios, de mucha ilusi\u00f3n, de espera, de alegr\u00eda, de puesta a punto, de hermanamiento, de echar una mano (o dos), de ajetreo, de sue\u00f1os.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5157 alignnone size-medium\" src=\"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/438162281_851754753656497_2832754338439091445_n-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" \/>Comenzamos a las 8:30 con el Rosario por las calles del barrio. A continuaci\u00f3n, celebramos la Eucarist\u00eda en el patio todos los alumnos del colegio, profesores, personal de administraci\u00f3n y servicios, familias, antiguos alumnos, Fundaci\u00f3n Don Bosco y cuantos asociados y devotos lo desearan.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Ma\u00f1ana de chocolate con churros, preparativos y \u00faltimos retoques al Paso de la Virgen mientras los alumnos participaban en el Grand Prix, con la inestimable colaboraci\u00f3n de Rub\u00e9n Garc\u00eda y su equipo: Melody, Juanmita, Pablo, Juanma y Juan Pedro.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5159 alignnone size-medium\" src=\"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/441498499_851754843656488_8168148543111207721_n-185x300.jpeg\" alt=\"\" width=\"185\" height=\"300\" \/>Por la tarde, el esperado momento de la procesi\u00f3n de Mar\u00eda Auxiliadora por las calles de La L\u00ednea hasta el Santuario de la Patrona, la Inmaculada Concepci\u00f3n. Nuestra Madre es acompa\u00f1ada durante el recorrido por numerosos fieles y curiosos que se acercan a contemplar el cortejo.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Ya de vuelta, con los pies doloridos pero el coraz\u00f3n alegre y contento, abrazos entre costaleros, la Salve en la entrada a la capilla y unas sevillanas muy emotivas como broche de oro a este d\u00eda tan intenso.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Evidentemente, todo ello no se logra con improvisaci\u00f3n, individualismo o desgana, sino que ha sido el trabajo y esfuerzo de muchas personas que generosamente regalan a la Virgen su tiempo y su buen hacer.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Desde el Consejo Local de la Archicofrad\u00eda de Mar\u00eda Auxiliadora queremos dar las gracias por el apoyo, acompa\u00f1amiento y disposici\u00f3n de todos los estamentos de la Casa y a todas las personas que de alg\u00fan u otro modo han colaborado para que la fiesta de Nuestra Madre haya sido realmente un GRAN D\u00cdA.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">En primer lugar, a la Comunidad Salesiana, garante de la devoci\u00f3n a Mar\u00eda Auxiliadora en La L\u00ednea. A Juanfran, titular de la Casa y Consiliario de Nuestra Asociaci\u00f3n, al que hemos descubierto en una nueva faceta de cantante; a Antonio Ortiz, por su siempre cercan\u00eda a la Asociaci\u00f3n; a Fran C\u00e1novas, por sus buenas noches en 2 cap\u00edtulos; y a D. Paco, por su generosidad y servicio.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Agradecer al Padre D. Ignacio y a toda la comunidad parroquial de Santiago Ap\u00f3stol su participaci\u00f3n en estas fiestas a Mar\u00eda.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Agradecer a Jes\u00fas Asencio su siempre exquisita imagen de Nuestra Madre para carteles y calendarios; a Juan Almansa su inestimable ayuda en los dise\u00f1os y los video reportajes de estos d\u00edas; a Jes\u00fas Mar\u00eda por la difusi\u00f3n de la Archicofrad\u00eda en el mundo de las Redes sociales; a Celia por el dise\u00f1o de diplomas y a Sergio y Yoly por las pulseras.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Agradecer a Arancha y Juan Carlos su exquisitez en la preparaci\u00f3n de la capilla donde se ha creado un clima de recogimiento y alabanza a Nuestra Madre; a todos los que participaron en la Bajada de la Virgen: los ni\u00f1os con poemas, Emma con su arte y David y Juan Pedro con su t\u00e9cnica. A Julio por su ayuda para que todo quede perfecto.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Agradecer a Soraya, el equipo directivo y todo el claustro de profesores; M\u00aa del Mar y todo el equipo de Pastoral; a Lale y personal de administraci\u00f3n y servicios, por toda la ayuda que nos ofrecen durante el a\u00f1o y la plena disposici\u00f3n durante las fiestas de Mayo.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Agradecer a todos los que han participado en la preparaci\u00f3n, puesta en marcha y desarrollo de la procesi\u00f3n: a todos los estamentos de la Casa; Aurelio, Javier, Jes\u00fas, \u00d3scar, Asociaci\u00f3n de Antiguos Alumnos y el equipo de costaleros de D. Bosco; Banda de M\u00fasica \u2018Ciudad de La L\u00ednea\u2019; la Hermandad de la Entrada Triunfal, en especial a Alberto Dur\u00e1n y Juan Correa con su equipo de fiscales; a todos los que preparan el paso para que salga tan majestuoso: Dory y su equipo de floristas; Darren, Alex, Lidia y Traverso por su dedicaci\u00f3n en tenerlo todo a punto; Angie y el equipo de capataces y costaleros de la Alegr\u00eda; A Iker por sus sevillanas; a los ni\u00f1os y ni\u00f1as de Primera Comuni\u00f3n de distintas parroquias de La L\u00ednea junto a sus catequistas.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Agradecer a Juan Franco y toda la corporaci\u00f3n municipal la facilidad y ayuda que nos presta en la organizaci\u00f3n de estos eventos; a la Polic\u00eda Local y a la Polic\u00eda Nacional por su siempre gran acompa\u00f1amiento. A Jos\u00e9 Manuel Pulpillo y al Consejo Local de Hermandades por su colaboraci\u00f3n.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Agradecer a Juanma y Juan Pedro por su siempre trabajo serio y profesional cuidando el m\u00e1s m\u00ednimo detalle.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Como no, agradecer a Restaurante De Costa, Mes\u00f3n Lolo y Restaurante Arabia su generosa contribuci\u00f3n en el avituallamiento de costaleros y m\u00fasicos.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">En definitiva, a todos nuestros asociados y devotos de la Virgen que han participado y animado la Novena, el Rosario de la Aurora, la Eucarist\u00eda solemne y la procesi\u00f3n.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Por \u00faltimo, un agradecimiento muy especial a D. Antonio Rodr\u00edguez, que fue nuestro Consiliario y que, desde las Puerta del Cielo, sabemos que nos ha estado ayudando y que ha disfrutado tanto como nosotros con la celebraci\u00f3n de este 24 de Mayo.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">De todo coraz\u00f3n, \u00a1\u00a1MUCHAS GRACIAS A TODOS!!<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">(disculpad si se nos olvida alguien pero, afortunadamente, son tantos a los que agradecer\u2026.)<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">El Consejo Local de ADMA<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 x1fey0fg xo1l8bm\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/mayosalesiano?__eep__=6&amp;__cft__[0]=AZVvEqWP_QqX_kzyiOF8NDWsflbmIjDExPFHm4Qx04FuCbhugkXW1vnqA3QpIINRBKGWbJYTweImMs-Xg4D8hkV6rn0Y1ytYE0-yY7Ouh0NyXdB2DdZncGTyEnTLMkr-Yh9vCo1g8XR53cpcGXTvSaahupQDWvUSMRsssSSKjhLrlO_0oyXoGHvvpGhGWP7b1Sd_X6f5cOaqoDDfD9PDW5rU&amp;__tn__=*NK-R\">#MayoSalesiano<\/a><\/span> <span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 x1fey0fg xo1l8bm\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/mar%C3%ADaauxiliadora?__eep__=6&amp;__cft__[0]=AZVvEqWP_QqX_kzyiOF8NDWsflbmIjDExPFHm4Qx04FuCbhugkXW1vnqA3QpIINRBKGWbJYTweImMs-Xg4D8hkV6rn0Y1ytYE0-yY7Ouh0NyXdB2DdZncGTyEnTLMkr-Yh9vCo1g8XR53cpcGXTvSaahupQDWvUSMRsssSSKjhLrlO_0oyXoGHvvpGhGWP7b1Sd_X6f5cOaqoDDfD9PDW5rU&amp;__tn__=*NK-R\">#Mar\u00edaAuxiliadora<\/a><\/span> <span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz x1sur9pj xkrqix3 x1fey0fg xo1l8bm\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/salesianoslal%C3%ADnea?__eep__=6&amp;__cft__[0]=AZVvEqWP_QqX_kzyiOF8NDWsflbmIjDExPFHm4Qx04FuCbhugkXW1vnqA3QpIINRBKGWbJYTweImMs-Xg4D8hkV6rn0Y1ytYE0-yY7Ouh0NyXdB2DdZncGTyEnTLMkr-Yh9vCo1g8XR53cpcGXTvSaahupQDWvUSMRsssSSKjhLrlO_0oyXoGHvvpGhGWP7b1Sd_X6f5cOaqoDDfD9PDW5rU&amp;__tn__=*NK-R\">#SalesianosLaL\u00ednea<\/a><\/span><\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=j0xfPWst4o0&#8243; _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb disabled_on=\u00bbon|on|on\u00bb disabled=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_video][et_pb_button button_url=\u00bbhttps:\/\/www.youtube.com\/channel\/UCQvMeT_zCqrQAVqmVGGQinA\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbYOUTUBE SALESIANO MUNDIAL\u00bb button_alignment=\u00bbleft\u00bb admin_label=\u00bbBot\u00f3n\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_radius=\u00bb39px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb disabled_on=\u00bbon|on|on\u00bb disabled=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por ADMA &#8211; Archicofrad\u00eda de MAr\u00eda Auxiliadora Y LLEG\u00d3 EL 25 DE MAYO\u2026. Y SEGUIMOS SO\u00d1ANDO Ayer fue un d\u00eda emotivo, de nervios, de mucha ilusi\u00f3n, de espera, de alegr\u00eda, de puesta a punto, de hermanamiento, de echar una mano (o dos), de ajetreo, de sue\u00f1os. Comenzamos a las 8:30 con el Rosario por las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5161,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[22,18,17],"tags":[],"class_list":["post-5165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capilla","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festividad de Mar\u00eda Auxiliadora - Centro Juvenil Acuarela<\/title>\n<meta name=\"description\" content=\"Festividad de Mar\u00eda Auxiliadora en nuestra Casa. Actividades desarrolladas por ADMA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festividad de Mar\u00eda Auxiliadora - Centro Juvenil Acuarela\" \/>\n<meta property=\"og:description\" content=\"Festividad de Mar\u00eda Auxiliadora en nuestra Casa. Actividades desarrolladas por ADMA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Juvenil Acuarela\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-28T11:21:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T08:55:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/444928590_851754816989824_5010105202881644680_n.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/#\\\/schema\\\/person\\\/ef1b42905476b83ae7c0566bc6342cf4\"},\"headline\":\"Festividad de Mar\u00eda Auxiliadora\",\"datePublished\":\"2024-05-28T11:21:21+00:00\",\"dateModified\":\"2025-08-04T08:55:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/\"},\"wordCount\":1165,\"image\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/05\\\/444928590_851754816989824_5010105202881644680_n.jpeg\",\"articleSection\":[\"Capilla\",\"Colegio\",\"Portada\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/\",\"url\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/\",\"name\":\"Festividad de Mar\u00eda Auxiliadora - Centro Juvenil Acuarela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/05\\\/444928590_851754816989824_5010105202881644680_n.jpeg\",\"datePublished\":\"2024-05-28T11:21:21+00:00\",\"dateModified\":\"2025-08-04T08:55:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/#\\\/schema\\\/person\\\/ef1b42905476b83ae7c0566bc6342cf4\"},\"description\":\"Festividad de Mar\u00eda Auxiliadora en nuestra Casa. Actividades desarrolladas por ADMA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/05\\\/444928590_851754816989824_5010105202881644680_n.jpeg\",\"contentUrl\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/05\\\/444928590_851754816989824_5010105202881644680_n.jpeg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/festividad-de-maria-auxiliadora-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festividad de Mar\u00eda Auxiliadora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/#website\",\"url\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/\",\"name\":\"Centro Juvenil Acuarela\",\"description\":\"P\u00e1gina oficial Salesianos La L\u00ednea de la Concepci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lalinea.salesianos.edu\\\/mjs\\\/#\\\/schema\\\/person\\\/ef1b42905476b83ae7c0566bc6342cf4\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae039c67a6e621564e1a6017ea99fd2d0f7377fb0341a51700c9f4546151a38e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae039c67a6e621564e1a6017ea99fd2d0f7377fb0341a51700c9f4546151a38e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae039c67a6e621564e1a6017ea99fd2d0f7377fb0341a51700c9f4546151a38e?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festividad de Mar\u00eda Auxiliadora - Centro Juvenil Acuarela","description":"Festividad de Mar\u00eda Auxiliadora en nuestra Casa. Actividades desarrolladas por ADMA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/","og_locale":"es_ES","og_type":"article","og_title":"Festividad de Mar\u00eda Auxiliadora - Centro Juvenil Acuarela","og_description":"Festividad de Mar\u00eda Auxiliadora en nuestra Casa. Actividades desarrolladas por ADMA.","og_url":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/","og_site_name":"Centro Juvenil Acuarela","article_published_time":"2024-05-28T11:21:21+00:00","article_modified_time":"2025-08-04T08:55:03+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/444928590_851754816989824_5010105202881644680_n.jpeg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/#article","isPartOf":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/"},"author":{"name":"Gestor Web","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/#\/schema\/person\/ef1b42905476b83ae7c0566bc6342cf4"},"headline":"Festividad de Mar\u00eda Auxiliadora","datePublished":"2024-05-28T11:21:21+00:00","dateModified":"2025-08-04T08:55:03+00:00","mainEntityOfPage":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/"},"wordCount":1165,"image":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/#primaryimage"},"thumbnailUrl":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/444928590_851754816989824_5010105202881644680_n.jpeg","articleSection":["Capilla","Colegio","Portada"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/","url":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/","name":"Festividad de Mar\u00eda Auxiliadora - Centro Juvenil Acuarela","isPartOf":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/#primaryimage"},"image":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/#primaryimage"},"thumbnailUrl":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/444928590_851754816989824_5010105202881644680_n.jpeg","datePublished":"2024-05-28T11:21:21+00:00","dateModified":"2025-08-04T08:55:03+00:00","author":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/#\/schema\/person\/ef1b42905476b83ae7c0566bc6342cf4"},"description":"Festividad de Mar\u00eda Auxiliadora en nuestra Casa. Actividades desarrolladas por ADMA.","breadcrumb":{"@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/#primaryimage","url":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/444928590_851754816989824_5010105202881644680_n.jpeg","contentUrl":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-content\/uploads\/sites\/4\/2024\/05\/444928590_851754816989824_5010105202881644680_n.jpeg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/festividad-de-maria-auxiliadora-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lalinea.salesianos.edu\/mjs\/"},{"@type":"ListItem","position":2,"name":"Festividad de Mar\u00eda Auxiliadora"}]},{"@type":"WebSite","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/#website","url":"https:\/\/lalinea.salesianos.edu\/mjs\/","name":"Centro Juvenil Acuarela","description":"P\u00e1gina oficial Salesianos La L\u00ednea de la Concepci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lalinea.salesianos.edu\/mjs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/lalinea.salesianos.edu\/mjs\/#\/schema\/person\/ef1b42905476b83ae7c0566bc6342cf4","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ae039c67a6e621564e1a6017ea99fd2d0f7377fb0341a51700c9f4546151a38e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ae039c67a6e621564e1a6017ea99fd2d0f7377fb0341a51700c9f4546151a38e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae039c67a6e621564e1a6017ea99fd2d0f7377fb0341a51700c9f4546151a38e?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/posts\/5165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/comments?post=5165"}],"version-history":[{"count":2,"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/posts\/5165\/revisions"}],"predecessor-version":[{"id":5167,"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/posts\/5165\/revisions\/5167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/media\/5161"}],"wp:attachment":[{"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/media?parent=5165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/categories?post=5165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lalinea.salesianos.edu\/mjs\/wp-json\/wp\/v2\/tags?post=5165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}